{"id":96,"count":11,"description":"","link":"https:\/\/www.ascona-locarno-run.ch\/en\/categoria-sponsor\/partners-en-2019\/","name":"Partners 2019","slug":"partners-en-2019","taxonomy":"portfolio_category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Partners 2019 Archivi - Ascona-Locarno Run<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Partners 2019 Archivi - Ascona-Locarno Run\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ascona-locarno-run.ch\/en\/categoria-sponsor\/partners-en-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Ascona-Locarno Run\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ascona-locarno-run.ch\/wp-content\/uploads\/2024\/03\/alr-FB-cover-2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"851\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/en\\\/categoria-sponsor\\\/partners-en-2019\\\/\",\"url\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/en\\\/categoria-sponsor\\\/partners-en-2019\\\/\",\"name\":\"Partners 2019 Archivi - Ascona-Locarno Run\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/en\\\/categoria-sponsor\\\/partners-en-2019\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/en\\\/categoria-sponsor\\\/partners-en-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Partners 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/\",\"name\":\"Ascona-Locarno Run\",\"description\":\"The perfect place for your run!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/#organization\",\"name\":\"Ascona-Locarno Run\",\"url\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logo-alr-colored.png\",\"contentUrl\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logo-alr-colored.png\",\"width\":800,\"height\":368,\"caption\":\"Ascona-Locarno Run\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ascona-locarno-run.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AsconaLocarnoRun\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ascona_locarno_run\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Partners 2019 Archivi - Ascona-Locarno Run","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Partners 2019 Archivi - Ascona-Locarno Run","og_url":"https:\/\/www.ascona-locarno-run.ch\/en\/categoria-sponsor\/partners-en-2019\/","og_site_name":"Ascona-Locarno Run","og_image":[{"width":851,"height":315,"url":"https:\/\/www.ascona-locarno-run.ch\/wp-content\/uploads\/2024\/03\/alr-FB-cover-2024.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ascona-locarno-run.ch\/en\/categoria-sponsor\/partners-en-2019\/","url":"https:\/\/www.ascona-locarno-run.ch\/en\/categoria-sponsor\/partners-en-2019\/","name":"Partners 2019 Archivi - Ascona-Locarno Run","isPartOf":{"@id":"https:\/\/www.ascona-locarno-run.ch\/#website"},"breadcrumb":{"@id":"https:\/\/www.ascona-locarno-run.ch\/en\/categoria-sponsor\/partners-en-2019\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ascona-locarno-run.ch\/en\/categoria-sponsor\/partners-en-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ascona-locarno-run.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Partners 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.ascona-locarno-run.ch\/#website","url":"https:\/\/www.ascona-locarno-run.ch\/","name":"Ascona-Locarno Run","description":"The perfect place for your run!","publisher":{"@id":"https:\/\/www.ascona-locarno-run.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ascona-locarno-run.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ascona-locarno-run.ch\/#organization","name":"Ascona-Locarno Run","url":"https:\/\/www.ascona-locarno-run.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ascona-locarno-run.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.ascona-locarno-run.ch\/wp-content\/uploads\/2024\/02\/logo-alr-colored.png","contentUrl":"https:\/\/www.ascona-locarno-run.ch\/wp-content\/uploads\/2024\/02\/logo-alr-colored.png","width":800,"height":368,"caption":"Ascona-Locarno Run"},"image":{"@id":"https:\/\/www.ascona-locarno-run.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AsconaLocarnoRun\/","https:\/\/www.instagram.com\/ascona_locarno_run\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.ascona-locarno-run.ch\/en\/wp-json\/wp\/v2\/portfolio_category\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ascona-locarno-run.ch\/en\/wp-json\/wp\/v2\/portfolio_category"}],"about":[{"href":"https:\/\/www.ascona-locarno-run.ch\/en\/wp-json\/wp\/v2\/taxonomies\/portfolio_category"}],"wp:post_type":[{"href":"https:\/\/www.ascona-locarno-run.ch\/en\/wp-json\/wp\/v2\/avada_portfolio?portfolio_category=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}